{"id":29569,"date":"2022-12-16T08:45:00","date_gmt":"2022-12-16T08:45:00","guid":{"rendered":"https:\/\/www.unavets.com\/unavets-celebra-su-ii-convencion-anual-summit-2022-reuniendo-a-mas-de-130-asistentes-que-conforman-el-grupo-de-espana-y-portugal\/"},"modified":"2024-09-23T10:33:03","modified_gmt":"2024-09-23T10:33:03","slug":"unavets-celebra-su-ii-convencion-anual-summit-2022-reuniendo-a-mas-de-130-asistentes-que-conforman-el-grupo-de-espana-y-portugal","status":"publish","type":"post","link":"https:\/\/www.unavets.com\/es\/unavets-celebra-su-ii-convencion-anual-summit-2022-reuniendo-a-mas-de-130-asistentes-que-conforman-el-grupo-de-espana-y-portugal\/","title":{"rendered":"UNAVETS celebra su II Convenci\u00f3n Anual SUMMIT 2022, reuniendo a m\u00e1s de 130 asistentes que conforman el grupo de Espa\u00f1a y Portugal"},"content":{"rendered":"<p style=\"text-align: justify;\">El pasado 28 al 30 de noviembre tuvo lugar la <span style=\"font-weight: bold;\">segunda Convenci\u00f3n Anual SUMMIT 2022 del Grupo UNAVETS <\/span>en Amoreira, Portugal. Al evento asistieron m\u00e1s de 130 directores de cl\u00ednicas y hospitales veterinarios de ambos pa\u00edses que forman el grupo, adem\u00e1s de invitados especiales, colaboradores, el equipo interno corporativo y socios l\u00edderes en el sector.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">El Congreso se celebr\u00f3 en el Hotel Praia D&#8217;El Rey Marriot Golf &amp; Beach Resort, al norte de Lisboa, donde los participantes tuvieron la oportunidad de asistir a unas interesantes jornadas y presentaciones preparadas por el equipo corporativo centradas en <span style=\"font-weight: bold;\">la evoluci\u00f3n y tendencias de futuro, el desarrollo tecnol\u00f3gico, expansi\u00f3n, marketing y la apuesta por el talento de las m\u00e1s de 900 personas que hoy forman el equipo de apoyo cl\u00ednico y empresaria<\/span>l.<\/p>\n<p style=\"text-align: justify;\">Los paneles tambi\u00e9n contaron con colaboradores especiales como Mar\u00eda Wilhelm, directora general de Earthship productora ejecutiva documentales centrados en los animales y los avances en sostenibilidad y conservaci\u00f3n, en colaboraci\u00f3n con National Geographic\/Disney+ y la fundaci\u00f3n James Cameron.<\/p>\n<p style=\"text-align: justify;\">Los participantes, adem\u00e1s, tuvieron tiempo de realizar divertidos proyectos de teambuilding y compartir momentos m\u00e1s distendidos para conocerse y compartir la conexi\u00f3n, vocaci\u00f3n y pasi\u00f3n por el sector veterinario.<\/p>\n<p style=\"text-align: justify;\">El \u00faltimo d\u00eda, tuvo lugar una cena especial en la que Junko Sheehan, Directora General de UNAVETS entreg\u00f3 una serie de premios que, reconocieron a las cl\u00ednicas y hospitales con resultados m\u00e1s destacados, a los equipos con m\u00e1s resiliencia ante los retos, al trabajador que trabaja m\u00e1s cerca a los equipos cl\u00ednicos y en resumen, a aquellas personas que con su esfuerzo han logrado que<span style=\"font-weight: bold;\"> a d\u00eda de hoy UNAVETS sea l\u00edder en el sector veterinario, con m\u00e1s de 90 centros en Espa\u00f1a y Portugal y con unas expectativas de gran crecimiento futuro<\/span>, que seguir\u00e1 brindando la mejor asistencia gracias a esta unificaci\u00f3n de recursos y profesionales.<\/p>\n<p style=\"text-align: justify;\">El final del evento fue considerado todo un \u00e9xito. En palabras de Ricard Bad\u00eda director del Hospital Veterinario Abat Marcet, \u201c<em>En el Congreso nos hemos sentido en una gran familia con proyectos y mucha ilusi\u00f3n. \u00a1Gracias a UNAVETS por el esfuerzo! Con vosotros hemos podido compartir experiencias y buen ambiente. Gracias a todos\u201d.<\/em><\/p>\n<p style=\"text-align: justify;\">En palabras de Ricard C\u00f3rdoba, director de la Cl\u00ednica Veterinaria Clinican: <em>\u201c\u00a1Muchas gracias a todos por la acogida a la familia UNAVETS! \u00a1Me he reforzado en la idea de que de todos los grupos que hay aqu\u00ed es el mejor!\u201d.<\/em><\/p>\n<p style=\"text-align: justify;\">Cristina Gonz\u00e1lez, directora de Cl\u00ednica Veterinaria Valvet Puerto Venecia<em>: \u201c\u00a1Un placer haberos conocido! Un placer haber compartido este viaje con vosotros, esta experiencia \u00a1y formar parte del mismo grupo! Un abrazo a todos\u201d. <\/em><\/p>\n<p style=\"text-align: justify;\">Marta Dell\u00e0, directora de la Cl\u00ednica Veterinaria Anubis: <em>\u201cHa sido todo incre\u00edble, emotivo, perfecto. Gracias UNAVETS por unir a grandes personas\u201d.<\/em><\/p>\n<p><strong>Sobre el Grupo UNAVETS<\/strong><\/p>\n<p>El Grupo UNAVETS ocupa una posici\u00f3n de liderazgo en el mercado de la asistencia veterinaria en Iberia (a trav\u00e9s de UNAVETS en Espa\u00f1a y Onevet en Portugal), desarrollando en 2,5 a\u00f1os un grupo que ofrece servicios compartidos y apoyo al desarrollo comercial a sus m\u00e1s de 91 centros veterinarios y m\u00e1s de 900 miembros del equipo. El grupo est\u00e1 formado por centros de referencia\/especializados, hospitales 24 horas, cl\u00ednicas de primera opini\u00f3n y consultorios, que garantizan un servicio c\u00f3modo y completo. Los planes de la compa\u00f1\u00eda son continuar con su estrategia de crecimiento en Iberia y otros pa\u00edses europeos, a la vez que desarrollar nuevas l\u00edneas de servicios, innovar con la apuesta digital internamente y con sus clientes, y promover la formaci\u00f3n y el desarrollo cient\u00edfico dentro del equipo cl\u00ednico. Para m\u00e1s informaci\u00f3n visite:<span>&nbsp;<\/span><a href=\"http:\/\/www.unavets.com\/es\">www.unavets.com\/es<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/8560088.fs1.hubspotusercontent-na1.net\/hubfs\/8560088\/Collage%20fotos%20resumen%20mes%20aesthetic%20moderno%20beige%20.png\" alt=\"Congreso Anual Unavets veterinarios Portugal y Espa\u00f1a 2022\" width=\"2000\" height=\"1600\" loading=\"lazy\" style=\"height: auto; max-width: 100%; width: 2000px;\"><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 28 al 30 de noviembre tuvo lugar el SUMMIT 2022 del Grupo UNAVETS en Portugal. Asistieron m\u00e1s de 130 directores de cl\u00ednicas y hospitales veterinarios<\/p>\n","protected":false},"author":1,"featured_media":29874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[840],"tags":[],"class_list":["post-29569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unavets"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.unavets.com\/es\/wp-json\/wp\/v2\/posts\/29569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unavets.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unavets.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unavets.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unavets.com\/es\/wp-json\/wp\/v2\/comments?post=29569"}],"version-history":[{"count":2,"href":"https:\/\/www.unavets.com\/es\/wp-json\/wp\/v2\/posts\/29569\/revisions"}],"predecessor-version":[{"id":29873,"href":"https:\/\/www.unavets.com\/es\/wp-json\/wp\/v2\/posts\/29569\/revisions\/29873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unavets.com\/es\/wp-json\/wp\/v2\/media\/29874"}],"wp:attachment":[{"href":"https:\/\/www.unavets.com\/es\/wp-json\/wp\/v2\/media?parent=29569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unavets.com\/es\/wp-json\/wp\/v2\/categories?post=29569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unavets.com\/es\/wp-json\/wp\/v2\/tags?post=29569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}